{"id":6936,"date":"2025-04-25T11:16:27","date_gmt":"2025-04-25T09:16:27","guid":{"rendered":"https:\/\/new.sportyneo.com\/?page_id=6936"},"modified":"2025-06-05T10:35:30","modified_gmt":"2025-06-05T08:35:30","slug":"landing-page-escrime","status":"publish","type":"page","link":"https:\/\/new.sportyneo.com\/en\/landing-page-escrime\/","title":{"rendered":"Landing Page Escrime"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6936\" class=\"elementor elementor-6936\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0aff1b5 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"0aff1b5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-764cb65 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"764cb65\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d52f000 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"d52f000\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b4e60d exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"2b4e60d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"4294\" height=\"1344\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/logo-sportyneo-bleu.png\" class=\"attachment-full size-full wp-image-1080\" alt=\"\" srcset=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/logo-sportyneo-bleu.png 4294w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/logo-sportyneo-bleu-300x94.png 300w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/logo-sportyneo-bleu-1024x321.png 1024w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/logo-sportyneo-bleu-768x240.png 768w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/logo-sportyneo-bleu-1536x481.png 1536w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/logo-sportyneo-bleu-2048x641.png 2048w\" sizes=\"(max-width: 4294px) 100vw, 4294px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db7b4ef exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"db7b4ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le partenaire financier des clubs d'escrime<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e82095c exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"e82095c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"cvGsUA direction-ltr align-start para-style-body\">Gagnez du temps dans la gestion de votre centre \u00e9questre ! Des paiements facilit\u00e9s en plusieurs fois pour l&rsquo;adh\u00e9rent et une avance de fond pour le gestionnaire. SPORTYNEO s\u2019occupe de tout, vous restez en selle !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d8344fd e-grid e-con-full wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"d8344fd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd8cd31 elementor-mobile-align-center exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-button\" data-id=\"bd8cd31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/new.sportyneo.com\/inscription-webinaire\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir la d\u00e9mo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b04667a elementor-mobile-align-center exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-button\" data-id=\"b04667a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/www.sportyneo.com\/mon-compte\/?form=register-association\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cr\u00e9er ma page<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f33784 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"2f33784\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d69eb2 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"0d69eb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"870\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2025\/04\/Visuel-accueil-Landing-Page-equitation-19.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-6941\" alt=\"\" srcset=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2025\/04\/Visuel-accueil-Landing-Page-equitation-19.png 1024w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2025\/04\/Visuel-accueil-Landing-Page-equitation-19-300x255.png 300w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2025\/04\/Visuel-accueil-Landing-Page-equitation-19-768x653.png 768w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2025\/04\/Visuel-accueil-Landing-Page-equitation-19-14x12.png 14w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a1d46f5 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no exad-sticky-section-no\" data-id=\"a1d46f5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ff8832a exad-glass-effect-no exad-sticky-section-no\" data-id=\"ff8832a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a6499bf exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"a6499bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos partenaires<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35a84ed elementor-arrows-position-inside elementor-pagination-position-outside exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image-carousel\" data-id=\"35a84ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;autoplay_speed&quot;:1000,&quot;speed&quot;:1500,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n                <div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"no\" href=\"https:\/\/www.linkedin.com\/feed\/update\/urn:li:activity:7086733053665939456\/\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Rugby-Aura.png\" alt=\"Rugby Aura\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"no\" href=\"https:\/\/new.sportyneo.com\/groupama-x-sportyneo\/\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2025\/02\/groupama-logo-2025-siteweb.png\" alt=\"Groupama\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"no\" href=\"https:\/\/medef43.fr\/fr\/actualite\/nouveaute-2024-reglement-des-cotisations-par-carte-bancaire\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Medef-Aura.png\" alt=\"Medef Aura\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"no\" href=\"https:\/\/www.linkedin.com\/feed\/update\/urn:li:activity:7044006322186387456\/\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/District-Meurthe-et-Moselle.png\" alt=\"District Meurthe et Moselle\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"no\" href=\"https:\/\/www.liguegolfaura.com\/nouveau-partenaire\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Ligue-Golf-Aura.png\" alt=\"Ligue Golf Aura\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"no\" href=\"https:\/\/www.facebook.com\/SportyNeoFR\/posts\/349148573987476\/\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Distric-MOsellan.png\" alt=\"Distric MOsellan\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"no\" href=\"https:\/\/alsace.fff.fr\/simple\/decouvrez-sportyneo-solution-daide-pour-vos-clubs\/\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/District-Alsace.png\" alt=\"District Alsace\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"no\" href=\"https:\/\/crepdll.org\/le-cre\/\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Fede-equitation-Pays-de-la-loire.png\" alt=\"Fede equitation Pays de la loire\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"no\" href=\"https:\/\/www.linkedin.com\/feed\/update\/urn:li:activity:7126285075083587584\/\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Fede-equitation-Aura.png\" alt=\"Fede equitation Aura\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"no\" href=\"https:\/\/www.linkedin.com\/posts\/sportyneofr_equitation-partenariat-aura-activity-7138672935426224128-HFQv\/?originalSubdomain=fr\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Fede-equitation-Grand-est.png\" alt=\"Fede equitation Grand est\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"no\" href=\"https:\/\/www.linkedin.com\/feed\/update\/urn:li:activity:7143619424271450112\/\" target=\"_blank\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Fede-equitation-Hauts-de-France.png\" alt=\"Fede equitation Hauts de France\" \/><\/figure><\/a><\/div>                <\/div>\n\t\t\t\t\t\t\t\t\t                        <div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t                        <div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n                            <i class=\"eicon-chevron-left\" aria-hidden=\"true\"><\/i>\n                            <span class=\"elementor-screen-only\">Pr\u00e9c\u00e9dent<\/span>\n                        <\/div>\n                        <div class=\"elementor-swiper-button elementor-swiper-button-next\">\n                            <i class=\"eicon-chevron-right\" aria-hidden=\"true\"><\/i>\n                            <span class=\"elementor-screen-only\">Suivant<\/span>\n                        <\/div>\n\t\t\t\t\t\t\t\t\t            <\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-a4ed755 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"a4ed755\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-493da5c e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"493da5c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78f792b exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"78f792b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Plus qu\u2019une plateforme d\u2019inscription,\nun \u00e9cosyst\u00e8me d\u00e9di\u00e9 \u00e0 la vie des clubs d'escrime<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c7e0e1 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"3c7e0e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Nos petits plus qui vous facilitent la vie !<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-67ce308 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"67ce308\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8d74aa4 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"8d74aa4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-55d1e0a e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"55d1e0a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9cef388 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"9cef388\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"870\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/12\/Visuels-page-inscriptions-paiements.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-3148\" alt=\"Inscription paiement en plusieurs fois tableau de bord de suivi\" srcset=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/12\/Visuels-page-inscriptions-paiements.png 1024w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/12\/Visuels-page-inscriptions-paiements-300x255.png 300w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/12\/Visuels-page-inscriptions-paiements-768x653.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d670a83 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"d670a83\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-541a138 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"541a138\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le paiement en plusieurs fois avec le <span class=\"underline-highlight\">versement int\u00e9gral<\/span> et imm\u00e9diat.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c7ee25 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"1c7ee25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Proposer le paiement en plusieurs fois \u00e0 vos licenci\u00e9s est essentiel pour leur permettre de soulager leur budget sport. Mais cela peut retarder le versement complet des cotisations pour les clubs.<\/p><p>Avec SPORTYNEO, vos adh\u00e9rents paient au choix en 1, 4 ou 10 fois, et vous collectez imm\u00e9diatement la totalit\u00e9, gr\u00e2ce \u00e0 une avance de fonds.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f93ada0 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-button\" data-id=\"f93ada0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/new.sportyneo.com\/accueil-club\/inscriptions-paiements\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-267e7f3 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"267e7f3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-04443f7 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"04443f7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c4871b0 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"c4871b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a65041d exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"a65041d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Plus besoin de g\u00e9rer les <span style=\"position: relative;color: inherit\">demandes d'annulation<span style=\"position: absolute;left: -7px;right: -7px;bottom: 0;height: 26px;background-color: #F8DD74;border-radius: 23px;z-index: -1\"><\/span><\/span> d'inscription<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5fd9b4 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"b5fd9b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Proposez une assurance annulation au moment des inscriptions : si votre adh\u00e9rent demande un remboursement, SPORTYNEO l&rsquo;indemnisera sur ses cotisations annuelles ou ses stages.<\/p><p>Avec l\u2019assurance facultative SPORTYNEO, d\u00e9finissez une politique claire d&rsquo;annulation et \u00e9vitez les pertes d\u2019argent. C\u2019est l\u2019assurance qui rembourse, pas vous !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a9d9c5 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-button\" data-id=\"4a9d9c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/new.sportyneo.com\/accueil-club\/assurance-interruption\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c001b6 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"4c001b6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2178364 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"2178364\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"870\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2025\/04\/Visuel-Landing-Page-equitation-18.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-6942\" alt=\"\" srcset=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2025\/04\/Visuel-Landing-Page-equitation-18.png 1024w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2025\/04\/Visuel-Landing-Page-equitation-18-300x255.png 300w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2025\/04\/Visuel-Landing-Page-equitation-18-768x653.png 768w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2025\/04\/Visuel-Landing-Page-equitation-18-14x12.png 14w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e191e94 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"e191e94\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f26e1bc e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"f26e1bc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0e4038b e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"0e4038b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c9469c exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"1c9469c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"position: relative;color: inherit\">Merchandising logot\u00e9<span style=\"position: absolute;left: -7px;right: -7px;bottom: 0;height: 26px;background-color: #f0c7ff;border-radius: 23px;z-index: -1\"><\/span><\/span> et commissions... sans rien faire !\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b0e325 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"3b0e325\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Avec la boutique en ligne SPORTYNEO, plus besoin de g\u00e9rer des stocks, des commandes group\u00e9es \u00e0 des fournisseurs et la distribution d&rsquo;\u00e9quipements logot\u00e9s.<\/p><p>S\u00e9lectionnez juste les articles qui vous correspondent parmi notre catalogue, et profitez ! Vos adh\u00e9rents passent commande lorsqu&rsquo;ils le souhaitent toute l&rsquo;ann\u00e9e, et sont livr\u00e9s directement chez eux.<\/p><p>Encore mieux : 10% de commission vont sont revers\u00e9s sur le montant total des commandes effectu\u00e9es dans l\u2019ann\u00e9e.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79e704b exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-button\" data-id=\"79e704b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/new.sportyneo.com\/accueil-club\/merchandising\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-295170d e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"295170d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c133172 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"c133172\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"870\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/12\/Visuels-page-merch.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-3141\" alt=\"boutique en ligne club de sport merchandising\" srcset=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/12\/Visuels-page-merch.png 1024w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/12\/Visuels-page-merch-300x255.png 300w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/12\/Visuels-page-merch-768x653.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5d55643 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"5d55643\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-08ef7e2 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"08ef7e2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-45d20c2 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"45d20c2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a8361fc exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"a8361fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"71\" height=\"50\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Maquette-Homepage-Site-v1-1-e1729593335851.png\" class=\"attachment-large size-large wp-image-1100\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-032cddd exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"032cddd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><span style=\"background-color: #f9dddf;padding-right: 10px;padding-left: 10px;padding-top: 7px;padding-bottom: 7px;border-radius: 10px\">PAIEMENT FRACTIONN\u00c9<\/span><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d4f66d4 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"d4f66d4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b41152d exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"b41152d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"50\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Maquette-Homepage-Site-v1-1-2-e1729593680692.png\" class=\"attachment-large size-large wp-image-1105\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61051c0 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"61051c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><span style=\"background-color: #f0c7ff;padding-right: 30px;padding-left: 30px;padding-top: 7px;padding-bottom: 7px;border-radius: 10px\">ASSURANCE<\/span><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2ec9190 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"2ec9190\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-782acca exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"782acca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"86\" height=\"50\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Maquette-Homepage-Site-v1-1-1-e1729593646806.png\" class=\"attachment-large size-large wp-image-1104\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-088b44b exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"088b44b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><span style=\"background-color: #d4e9e9;padding-right: 20px;padding-left: 20px;padding-top: 7px;padding-bottom: 7px;border-radius: 10px\">POUVOIR D\u2019ACHAT<\/span><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6966d17 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"6966d17\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-da74a1a exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"da74a1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"63\" height=\"50\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Maquette-Homepage-Site-v1-1-3-e1729593787195.png\" class=\"attachment-large size-large wp-image-1106\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9629b84 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"9629b84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><span style=\"background-color: #cdd7fa;padding-right: 20px;padding-left: 20px;padding-top: 7px;padding-bottom: 7px;border-radius: 10px\">MERCHANDISING<\/span><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-146e802 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"146e802\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-28679a2 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"28679a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Offrir un parcours d\u2019adh\u00e9sion  <br>simple &amp; rapide  \u00e0 vos licenci\u00e9s d'escrime<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a50ae0 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"3a50ae0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Nous cr\u00e9ons ensemble votre page Club en moins d&rsquo;une semaine.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ee4f3bf e-grid e-con-full wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"ee4f3bf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ecaec47 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"ecaec47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"870\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2025\/06\/Design-sans-titre-71.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-7971\" alt=\"\" srcset=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2025\/06\/Design-sans-titre-71.png 1024w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2025\/06\/Design-sans-titre-71-300x255.png 300w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2025\/06\/Design-sans-titre-71-768x653.png 768w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2025\/06\/Design-sans-titre-71-14x12.png 14w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6ef2ba faq exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-toggle\" data-id=\"d6ef2ba\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"faq\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2251\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2251\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">01.  Je cr\u00e9e la page de mon club d'escrime<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2251\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2251\"><p>Je cr\u00e9e la page de mon club d&rsquo;escrime et je mets en ligne mes cotisations, stages et tarifs sp\u00e9ciaux.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2252\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2252\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">02. Je s\u00e9lectionne mes articles de boutique en ligne<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2252\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2252\"><p>Je s\u00e9lectionne les goodies &amp; accessoires que mes licenci\u00e9s peuvent commander en toute autonomie.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2253\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2253\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">03.  J\u2019envoie le lien de ma page \u00e0 mes licenci\u00e9s d'escrime<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2253\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2253\"><p><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Je communique l\u2019url de ma page Club \u00e0 mes licenci\u00e9s.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2254\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2254\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">04.  Je suis mes inscriptions et mes comptes en toute simplicit\u00e9              <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2254\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2254\"><p>Je me rends sur mon tableau de bord pour suivre mes statistiques de vente et d&rsquo;inscription en temps r\u00e9el.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0cfb8a6 e-grid e-con-full wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"0cfb8a6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7969e34 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"7969e34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Je peux cr\u00e9er ma page maintenant pour tester ?<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5e7478 elementor-mobile-align-center exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-button\" data-id=\"b5e7478\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.sportyneo.com\/mon-compte\/?form=register-association\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Je cr\u00e9e ma page pour mon club d'escrime<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b3b3b04 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default exad-glass-effect-no wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no exad-sticky-section-no\" data-id=\"b3b3b04\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0c2f999 exad-glass-effect-no exad-sticky-section-no\" data-id=\"0c2f999\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-51ae41d elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no exad-sticky-section-no\" data-id=\"51ae41d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-66f35c7 exad-glass-effect-no exad-sticky-section-no\" data-id=\"66f35c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da6e37d exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"da6e37d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ce qu'en disent nos clients<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-291a9d2 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"291a9d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Parce que ce sont eux qui en parlent le mieux\u2026<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-358b498 elementor-widget-divider--view-line exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-divider\" data-id=\"358b498\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8393393 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no exad-sticky-section-no\" data-id=\"8393393\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-83e2526 exad-glass-effect-no exad-sticky-section-no\" data-id=\"83e2526\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a9ace1 elementor-testimonial--layout-image_above elementor-testimonial--skin-default elementor-testimonial--align-center elementor-arrows-yes elementor-pagination-type-bullets exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-testimonial-carousel\" data-id=\"1a9ace1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;loop&quot;:&quot;yes&quot;,&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"Depuis d\u00e9cembre, on a encaiss\u00e9 un CA, juste avec SPORTYNEO, d\u2019un peu plus de 20 000\u20ac. C\u2019est un vrai avantage financier, car si on avait du passer par une banque, elle nous aurait pris 4% dessus.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Sylvain DUFOURNEAUD<\/span><span class=\"elementor-testimonial__title\">Dirigeant du Poney Club de Val-de-Sa\u00f4ne<\/span><\/cite>\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/12\/Sylvain-DUFOURNEAUD-1.jpg\" alt=\"Sylvain DUFOURNEAUD\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"SPORTYNEO nous permet d\u2019avoir les r\u00e8glements avant le d\u00e9but du stage alors qu\u2019avant on courait tout le temps apr\u00e8s les r\u00e8glements.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Stanislas TERRIER<\/span><span class=\"elementor-testimonial__title\">Responsable de l\u2019\u00e9cole de Tennis d\u2019Annecy<\/span><\/cite>\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/12\/Stanislas-TERRIER-1.jpg\" alt=\"Stanislas TERRIER\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"C\u2019est une diversit\u00e9 de paiement pour nos adh\u00e9rents et un gain de temps pour nous au niveau administratif et suivi des commandes.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Dominique TEIXEIRA<\/span><span class=\"elementor-testimonial__title\">Responsable sportif du F.C. Geispolsheim<\/span><\/cite>\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/12\/Dominique-TEIXEIRA-1.jpg\" alt=\"Dominique TEIXEIRA\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"SPORTYNEO nous permet de nous focaliser sur d\u2019autres domaines et de ne pas toujours courir apr\u00e8s les diff\u00e9rents r\u00e8glements.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">David MAIRE<\/span><span class=\"elementor-testimonial__title\">Dirigeant du club de l\u2019AS Ludres<\/span><\/cite>\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/12\/David-MAIRE-1.jpg\" alt=\"David MAIRE\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\"L'avantage de SPORTYNEO, c'est que nous avons une tra\u00e7abilit\u00e9 qui est tr\u00e8s simple, puisque tous les flux financiers passent par le dashboard de l'association.\"\t\t\t\t\t<\/div>\n\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Adrien TURBIL<\/span><span class=\"elementor-testimonial__title\">Responsable Administratif et Communication du Rouen Normandie Rugby <\/span><\/cite>\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/12\/Adrien-TURBIL-1.jpg\" alt=\"Adrien TURBIL\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00e9c\u00e9dent\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Suivant\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-36b1710 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"36b1710\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-95a28bb e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"95a28bb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-119b71a e-grid e-con-full wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"119b71a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b4386e8 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"b4386e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">J&rsquo;aimerais utiliser SPORTYNEO pour mon club d&rsquo;escrime<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c84ed7 elementor-mobile-align-center exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-button\" data-id=\"1c84ed7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.sportyneo.com\/mon-compte\/?form=register-association\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cr\u00e9er ma page<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8a3f8df e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"8a3f8df\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2fca02d exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"2fca02d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">C\u2019est gratuit, c\u2019est pratique, c\u2019est sans engagement... \nComment je m\u2019inscris ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-27585fe e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"27585fe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-056cc52 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"056cc52\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b657cde e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"b657cde\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-68446bb e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"68446bb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-348133d exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"348133d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"254\" height=\"254\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Overworked.png\" class=\"attachment-large size-large wp-image-1141\" alt=\"\" srcset=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Overworked.png 254w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Overworked-150x150.png 150w\" sizes=\"(max-width: 254px) 100vw, 254px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4ed133 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"c4ed133\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Je prends contact avec\nSPORTYNEO<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fdb5db exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"2fdb5db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Pour voir concr\u00e8tement \u00e0 quoi ressemble la plateforme, et poser toutes mes questions. <\/span><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Je peux aussi directement cr\u00e9er ma page Club en autonomie.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7517373 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"7517373\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/1-3.png\" class=\"attachment-large size-large wp-image-2032\" alt=\"\" srcset=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/1-3.png 300w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/1-3-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6324d67 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"6324d67\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57ba3e8 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"57ba3e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"254\" height=\"254\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Partnership.png\" class=\"attachment-large size-large wp-image-1139\" alt=\"\" srcset=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Partnership.png 254w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Partnership-150x150.png 150w\" sizes=\"(max-width: 254px) 100vw, 254px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-603c9aa exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"603c9aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Je signe la convention de partenariat<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22336c2 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"22336c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">SPORTYNEO est gratuit, mais l\u2019utilisation de la plateforme est soumis \u00e0 la signature d\u2019une convention, afin qu\u2019on puisse vous verser vos recettes et vos commissions.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03aee28 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"03aee28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/2-2.png\" class=\"attachment-large size-large wp-image-2031\" alt=\"\" srcset=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/2-2.png 300w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/2-2-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9134fd6 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"9134fd6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b443df exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"6b443df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"254\" height=\"254\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Checklist.png\" class=\"attachment-large size-large wp-image-1142\" alt=\"\" srcset=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Checklist.png 254w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Checklist-150x150.png 150w\" sizes=\"(max-width: 254px) 100vw, 254px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce899e6 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"ce899e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Je cr\u00e9e ma page Club avec mes activit\u00e9s<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56fe19e exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"56fe19e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Je rentre mes cotisations, mes stages, mes r\u00e9ductions, et je s\u00e9lectionne mes articles de merchandising. <\/span><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Et hop, je peux recevoir mes inscriptions et mes commandes !<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-577e6b9 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"577e6b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/3-1.png\" class=\"attachment-large size-large wp-image-2033\" alt=\"\" srcset=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/3-1.png 300w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/3-1-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47f5b6ae elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no exad-sticky-section-no\" data-id=\"47f5b6ae\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-683dd3bf exad-glass-effect-no exad-sticky-section-no\" data-id=\"683dd3bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ef7ce92 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"1ef7ce92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Questions fr\u00e9quentes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a7cf3c8 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-toggle\" data-id=\"6a7cf3c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1781\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1781\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-arrow-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M413.1 222.5l22.2 22.2c9.4 9.4 9.4 24.6 0 33.9L241 473c-9.4 9.4-24.6 9.4-33.9 0L12.7 278.6c-9.4-9.4-9.4-24.6 0-33.9l22.2-22.2c9.5-9.5 25-9.3 34.3.4L184 343.4V56c0-13.3 10.7-24 24-24h32c13.3 0 24 10.7 24 24v287.4l114.8-120.5c9.3-9.8 24.8-10 34.3-.4z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">La plateforme est-elle uniquement accessible aux associations ?     <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1781\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1781\"><p><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Il n\u2019est pas n\u00e9cessaire d\u2019avoir le statut d\u2019association pour b\u00e9n\u00e9ficier de notre plateforme. Elle est accessible \u00e0 tous les clubs, de toutes tailles, que ce soit des assos ou des entreprises comme des centres \u00e9questres.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1782\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1782\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-arrow-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M413.1 222.5l22.2 22.2c9.4 9.4 9.4 24.6 0 33.9L241 473c-9.4 9.4-24.6 9.4-33.9 0L12.7 278.6c-9.4-9.4-9.4-24.6 0-33.9l22.2-22.2c9.5-9.5 25-9.3 34.3.4L184 343.4V56c0-13.3 10.7-24 24-24h32c13.3 0 24 10.7 24 24v287.4l114.8-120.5c9.3-9.8 24.8-10 34.3-.4z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">La plateforme est-elle r\u00e9serv\u00e9e aux clubs de sport uniquement ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1782\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1782\"><p><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Elle a initialement \u00e9t\u00e9 con\u00e7ue pour les clubs de sport. Mais les \u00e9coles de musique, clubs de th\u00e9\u00e2tre, BDE, AS sportives (etc.) rencontrent les m\u00eames probl\u00e9matiques, et peuvent utiliser notre plateforme sans soucis.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1783\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1783\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-arrow-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M413.1 222.5l22.2 22.2c9.4 9.4 9.4 24.6 0 33.9L241 473c-9.4 9.4-24.6 9.4-33.9 0L12.7 278.6c-9.4-9.4-9.4-24.6 0-33.9l22.2-22.2c9.5-9.5 25-9.3 34.3.4L184 343.4V56c0-13.3 10.7-24 24-24h32c13.3 0 24 10.7 24 24v287.4l114.8-120.5c9.3-9.8 24.8-10 34.3-.4z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Est-ce que la solution est vraiment gratuite pour mon Club ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1783\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1783\"><p><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Absolument, aucun frais cach\u00e9s, toutes nos fonctionnalit\u00e9s sont 100% gratuites pour les clubs.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1784\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1784\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-arrow-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M413.1 222.5l22.2 22.2c9.4 9.4 9.4 24.6 0 33.9L241 473c-9.4 9.4-24.6 9.4-33.9 0L12.7 278.6c-9.4-9.4-9.4-24.6 0-33.9l22.2-22.2c9.5-9.5 25-9.3 34.3.4L184 343.4V56c0-13.3 10.7-24 24-24h32c13.3 0 24 10.7 24 24v287.4l114.8-120.5c9.3-9.8 24.8-10 34.3-.4z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Comment vous r\u00e9mun\u00e9rez-vous si la solution est gratuite ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1784\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1784\"><p>Notre r\u00e9mun\u00e9ration se base sur un autre business model, \u00e0 savoir des commissions sur le service facultatif d\u2019assurance, les bons d&rsquo;achat ou le merchandising.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1785\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1785\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-arrow-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M413.1 222.5l22.2 22.2c9.4 9.4 9.4 24.6 0 33.9L241 473c-9.4 9.4-24.6 9.4-33.9 0L12.7 278.6c-9.4-9.4-9.4-24.6 0-33.9l22.2-22.2c9.5-9.5 25-9.3 34.3.4L184 343.4V56c0-13.3 10.7-24 24-24h32c13.3 0 24 10.7 24 24v287.4l114.8-120.5c9.3-9.8 24.8-10 34.3-.4z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Que se passe-t-il si le prelevement de l'un de mes adh\u00e9rents ne passe pas sur un paiement en plusieurs fois (carte obsol\u00e8te, fond insuffisant,...) ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1785\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1785\"><p>Notre partenaire bancaire s&rsquo;occupe de contacter votre adh\u00e9rent pour mettre \u00e0 jours ses informations de paiement ou reprogrammer un pr\u00e9l\u00e8vement. Dans tous les cas votre tresorerie est s\u00e9curis\u00e9. Sportyneo ne viendra jamais vous demander un remboursement suite \u00e0 un impay\u00e9 de l&rsquo;un de vos adh\u00e9rent.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1786\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1786\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-arrow-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M413.1 222.5l22.2 22.2c9.4 9.4 9.4 24.6 0 33.9L241 473c-9.4 9.4-24.6 9.4-33.9 0L12.7 278.6c-9.4-9.4-9.4-24.6 0-33.9l22.2-22.2c9.5-9.5 25-9.3 34.3.4L184 343.4V56c0-13.3 10.7-24 24-24h32c13.3 0 24 10.7 24 24v287.4l114.8-120.5c9.3-9.8 24.8-10 34.3-.4z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Les adh\u00e9rents peuvent-ils r\u00e9gler leurs cotisations & stages par d\u2019autres moyens qu\u2019en CB ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1786\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1786\"><p><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Tout \u00e0 fait. Chaque Club peut d\u00e9cider d\u2019activer uniquement la CB (ce que nous recommandons pour gagner du temps et \u00e9viter la paperasserie), ou de proposer d\u2019autres moyens comme les ch\u00e8ques et esp\u00e8ces.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1787\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1787\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-arrow-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M413.1 222.5l22.2 22.2c9.4 9.4 9.4 24.6 0 33.9L241 473c-9.4 9.4-24.6 9.4-33.9 0L12.7 278.6c-9.4-9.4-9.4-24.6 0-33.9l22.2-22.2c9.5-9.5 25-9.3 34.3.4L184 343.4V56c0-13.3 10.7-24 24-24h32c13.3 0 24 10.7 24 24v287.4l114.8-120.5c9.3-9.8 24.8-10 34.3-.4z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Peut-on g\u00e9rer les r\u00e9ductions comme le Pass\u2019Sport, Pass R\u00e9gion, ch\u00e8que ANCV, etc. ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1787\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1787\"><p><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Oui la plateforme g\u00e8re tout \u00e7a. Vous pouvez m\u00eame ajouter des r\u00e9ductions personnalis\u00e9es comme des r\u00e9ductions famille, des r\u00e9ductions de la mairie&#8230;<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1788\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1788\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-arrow-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M413.1 222.5l22.2 22.2c9.4 9.4 9.4 24.6 0 33.9L241 473c-9.4 9.4-24.6 9.4-33.9 0L12.7 278.6c-9.4-9.4-9.4-24.6 0-33.9l22.2-22.2c9.5-9.5 25-9.3 34.3.4L184 343.4V56c0-13.3 10.7-24 24-24h32c13.3 0 24 10.7 24 24v287.4l114.8-120.5c9.3-9.8 24.8-10 34.3-.4z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Peut-on couvrir tous les membres de son Club par l\u2019assurance interruption de pratique ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1788\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1788\"><p>Oui c\u2019est d\u00e9sormais possible. Suite \u00e0 la demande de nombreux Clubs, nous avons mis en place cette nouvelle solution facultative. Le co\u00fbt de l\u2019assurance \u00e9tant en moyenne de 5%, nous conseillons aux clubs d&rsquo;augmenter le tarif de leur inscription de 5%, pour couvrir tous ses membres et n\u2019avoir aucun frais suppl\u00e9mentaire. Le Club peut aussi d\u00e9cider de prendre en charge ce co\u00fbt. Dans tous les cas, avec cette assurance, si l\u2019un de ses adh\u00e9rents se blesse durant l\u2019ann\u00e9e, d\u00e9m\u00e9nage, rencontre des soucis de sant\u00e9, ou change simplement d\u2019avis (stages uniquement), l\u2019assurance pourra les rembourser et le Club n\u2019aura aucune sortie d\u2019argent impr\u00e9vue.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1789\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-1789\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-arrow-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M413.1 222.5l22.2 22.2c9.4 9.4 9.4 24.6 0 33.9L241 473c-9.4 9.4-24.6 9.4-33.9 0L12.7 278.6c-9.4-9.4-9.4-24.6 0-33.9l22.2-22.2c9.5-9.5 25-9.3 34.3.4L184 343.4V56c0-13.3 10.7-24 24-24h32c13.3 0 24 10.7 24 24v287.4l114.8-120.5c9.3-9.8 24.8-10 34.3-.4z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Si l\u2019assurance est prise individuellement par mes licenci\u00e9s, quel est son co\u00fbt ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1789\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-1789\"><p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">L\u2019assurance interruption de pratique, pour les cotisations annuelles, co\u00fbtera \u00e0 l\u2019adh\u00e9rent 4,5% du montant de sa cotisation. Concr\u00e8tement, cela veut dire que pour une cotisation de 100\u20ac, il paiera 4,50\u20ac en plus.<\/span><\/p><p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">L\u2019assurance interruption de pratique pour les stages est de 5,3% du montant du stage. Elle est un peu plus \u00e9lev\u00e9e car elle comprend davantage de garanties, comme le changement d\u2019avis. Si votre adh\u00e9rent change d\u2019avis la veille de son stage, sans aucun justificatif, l\u2019assurance lui rembourse 70% du montant vers\u00e9 pour le stage, et vous gardez l\u2019int\u00e9gralit\u00e9. C\u2019est donc une belle garantie pour les Clubs, d\u2019o\u00f9 la demande des Clubs de pouvoir assurer tous leurs membres d\u2019office.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-17810\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-17810\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-arrow-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M413.1 222.5l22.2 22.2c9.4 9.4 9.4 24.6 0 33.9L241 473c-9.4 9.4-24.6 9.4-33.9 0L12.7 278.6c-9.4-9.4-9.4-24.6 0-33.9l22.2-22.2c9.5-9.5 25-9.3 34.3.4L184 343.4V56c0-13.3 10.7-24 24-24h32c13.3 0 24 10.7 24 24v287.4l114.8-120.5c9.3-9.8 24.8-10 34.3-.4z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Je ne comprends pas la diff\u00e9rence entre la \u201cboutique du Club\u201d et la \u201cboutique en ligne\u201d ?    <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-17810\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-17810\"><p>Sur la boutique du Club, vous pouvez mettre tous les v\u00eatements ou \u00e9quipements logot\u00e9s qui sont g\u00e9r\u00e9s par le Club. Dans ce cas, c\u2019est le Club qui s\u2019occupe de toute l\u2019organisation des commandes, ce qui peut \u00eatre chronophage, mais parfois n\u00e9cessaire.<\/p><p>En compl\u00e9ment, nous proposant une boutique en ligne avec nos propres fournisseurs, dont le gros avantage est de tout g\u00e9rer pour lib\u00e9rer du temps aux Clubs. Comme sur un site e-commerce, les adh\u00e9rents peuvent aller quand ils le d\u00e9sirent et toute l\u2019ann\u00e9e sur la page Club, et commander T-shirt, jogging, casquettes, mugs (etc.) au logo du Club. Ils re\u00e7oivent leur commande \u00e0 domicile.<\/p><p>Pour le Club, plus besoin d&rsquo;attendre et de relancer chaque membre avant de lancer une commande, ni d&rsquo;avoir un minimum de quantit\u00e9, \u00e0 distribuer ensuite la bonne taille \u00e0 chacun, etc.<\/p><p>Et surtout, le Club recevra 10% de commission sur le total des commandes annuelles de ses adh\u00e9rents, sans rien faire !<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-17811\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-17811\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-arrow-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M413.1 222.5l22.2 22.2c9.4 9.4 9.4 24.6 0 33.9L241 473c-9.4 9.4-24.6 9.4-33.9 0L12.7 278.6c-9.4-9.4-9.4-24.6 0-33.9l22.2-22.2c9.5-9.5 25-9.3 34.3.4L184 343.4V56c0-13.3 10.7-24 24-24h32c13.3 0 24 10.7 24 24v287.4l114.8-120.5c9.3-9.8 24.8-10 34.3-.4z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">L'assurance fonctionne-t-elle pour les forfaits ou les cartes s\u00e9ances ?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-17811\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-17811\"><p>Oui ! Notre assurance \u00ab\u00a0Licence sportive\u00a0\u00bb couvre \u00e9galement ce type d&rsquo;offre. Il suffit que la p\u00e9riode de validit\u00e9 des forfaits et cartes s\u00e9ances soient bien renseign\u00e9es lors du param\u00e9trage de votre activit\u00e9.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-b6fe89a elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"b6fe89a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-beb63fc e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"beb63fc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-513796a e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"513796a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b73acab e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"b73acab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e4577b exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"3e4577b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ils parlent de nous : <br><span style=\"position: relative;color: inherit\">Haras de la chaussette<span style=\"position: absolute;left: -7px;right: -7px;bottom: 0;height: 26px;background-color: #F8DD74;border-radius: 23px;z-index: -1\"><\/span><\/span> <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a9af7a exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"5a9af7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00ab\u00a0Gr\u00e2ce \u00e0 SPORTYNEO, nous avons enfin une solution simple et efficace pour g\u00e9rer les \u00e9quipements de notre centre \u00e9questre. Plus besoin de g\u00e9rer les stocks ou les commandes group\u00e9es, nos cavaliers commandent directement en ligne et sont livr\u00e9s chez eux. Le paiement en plusieurs fois est un vrai plus pour nos adh\u00e9rents, et nous, nous recevons les fonds imm\u00e9diatement. Sans oublier l\u2019assurance annulation qui nous prot\u00e8ge des impr\u00e9vus. Une vraie r\u00e9volution pour notre club !\u00a0\u00bb<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64f81f3 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"64f81f3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0259838 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"0259838\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"870\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2025\/04\/Visuel-Landing-Page-equitation.png\" class=\"attachment-large size-large wp-image-5968\" alt=\"\" srcset=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2025\/04\/Visuel-Landing-Page-equitation.png 1024w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2025\/04\/Visuel-Landing-Page-equitation-300x255.png 300w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2025\/04\/Visuel-Landing-Page-equitation-768x653.png 768w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2025\/04\/Visuel-Landing-Page-equitation-14x12.png 14w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac87908 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no exad-sticky-section-no\" data-id=\"ac87908\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0357555 exad-glass-effect-no exad-sticky-section-no\" data-id=\"0357555\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-43bb9dd elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no exad-sticky-section-no\" data-id=\"43bb9dd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-045f728 exad-glass-effect-no exad-sticky-section-no\" data-id=\"045f728\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7e65fc animated-slow exad-sticky-section-no exad-glass-effect-no elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a7e65fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Je rejoins l\u2019\u00e9cosyst\u00e8me de\nSPORTYNEO !<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-014f514 elementor-icon-list--layout-inline elementor-mobile-align-center elementor-list-item-link-full_width exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-icon-list\" data-id=\"014f514\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Paiements <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Merchandising<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Assurance<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bons d'achat<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3573bd2 exad-glass-effect-no exad-sticky-section-no\" data-id=\"3573bd2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7685108 e-grid e-con-full wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"7685108\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ecca795 elementor-align-right elementor-mobile-align-center exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-button\" data-id=\"ecca795\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.sportyneo.com\/mon-compte\/?form=register-association\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Je cr\u00e9e ma page Club<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e0c09e elementor-align-left elementor-mobile-align-center exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-button\" data-id=\"6e0c09e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/new.sportyneo.com\/inscription-webinaire\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir la d\u00e9mo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-f42cfb3 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"f42cfb3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-959512b exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"959512b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nos articles<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cb443b4 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"cb443b4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-52fa0a8 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"52fa0a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-dc74d88 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"dc74d88\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-141a5d3 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"141a5d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"451\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Content2.png\" class=\"attachment-large size-large wp-image-1182\" alt=\"\" srcset=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Content2.png 680w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Content2-300x199.png 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d7adaa exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"8d7adaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Alec Whitten \u2022 17 Jan 2024<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a614a4d exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"a614a4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Je prends contact avec\nSPORTYNEO<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f217888 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"f217888\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">&#8230; pour voir concr\u00e8tement \u00e0 quoi ressemble la plateforme, et poser toutes mes questions.<\/span><\/p><p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Si je pr\u00e9f\u00e8re, je peux aussi directement cr\u00e9er ma page Club en autonomie.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f63021 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"5f63021\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e1371e9 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"e1371e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"451\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Content2.png\" class=\"attachment-large size-large wp-image-1182\" alt=\"\" srcset=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Content2.png 680w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Content2-300x199.png 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ee87f1 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"2ee87f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Alec Whitten \u2022 17 Jan 2024<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76d8c19 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"76d8c19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Je signe la convention de partenariat<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d42fb48 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"d42fb48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">SPORTYNEO est gratuit, mais l\u2019utilisation de la plateforme est soumis \u00e0 la signature d\u2019une convention, afin qu\u2019on puisse vous verser vos recettes et vos commissions.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f237e6a e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"f237e6a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c311af exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"5c311af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"451\" src=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Content2.png\" class=\"attachment-large size-large wp-image-1182\" alt=\"\" srcset=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Content2.png 680w, https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/Content2-300x199.png 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb2b1f0 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"bb2b1f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Alec Whitten \u2022 17 Jan 2024<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d63c16 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"1d63c16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Je cr\u00e9e ma page Club avec mes activit\u00e9s<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc1e7df exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"bc1e7df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">&#8230; pour voir concr\u00e8tement \u00e0 quoi ressemble la plateforme, et poser toutes mes questions.<\/span><\/p><p class=\"cvGsUA direction-ltr align-start para-style-body\"><span class=\"OYPEnA font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Je peux aussi cr\u00e9er ma page Club en autonomie.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcff4c3 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"bcff4c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b367596 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"b367596\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b6f1e6 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"3b6f1e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84dd638 elementor-align-center exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-button\" data-id=\"84dd638\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9couvrir<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9a91d4 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no exad-sticky-section-no\" data-id=\"9a91d4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-71dc5b95 exad-glass-effect-no exad-sticky-section-no\" data-id=\"71dc5b95\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2fd4bb3e exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"2fd4bb3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Inscription \u00e0 la newsletter<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-407891bf exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"407891bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Restez inform\u00e9s des derni\u00e8res nouvelles, annonces et bons plans SPORTYNEO.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-309c84df exad-glass-effect-no exad-sticky-section-no\" data-id=\"309c84df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e572d5c eael-wpforms-form-button-custom exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-eael-wpforms\" data-id=\"1e572d5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"eael-contact-form eael-wpforms eael-wpforms-align-default\">\n                                <div class=\"wpforms-container inline-fields\" id=\"wpforms-1355\"><form id=\"wpforms-form-1355\" class=\"wpforms-validate wpforms-form\" data-formid=\"1355\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/6936\" data-token=\"566202a6d5507a109c0c92eb057d4375\" data-token-time=\"1788325625\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-1355-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1355-field_1\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-1355-field_1\" class=\"wpforms-field-small wpforms-field-required\" name=\"wpforms[fields][1]\" placeholder=\"Votre email ici\" spellcheck=\"false\" required><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-1355-field-hp\" class=\"wpforms-field-label\">Message<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-1355-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"1355\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/new.sportyneo.com\/en\/wp-json\/wp\/v2\/pages\/6936\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-1355\" class=\"wpforms-submit inline-fields\" data-alt-text=\"Demande en cours d&#039;envoi...\" data-submit-text=\"S&#039;inscrire\" aria-live=\"assertive\" value=\"wpforms-submit\">S&#039;inscrire<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->            <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Le partenaire financier des clubs d&rsquo;escrime Gagnez du temps dans la gestion de votre centre \u00e9questre ! Des paiements facilit\u00e9s en plusieurs fois pour l&rsquo;adh\u00e9rent et une avance de fond pour le gestionnaire. SPORTYNEO s\u2019occupe de tout, vous restez en selle ! Voir la d\u00e9mo Cr\u00e9er ma page Nos partenaires Pr\u00e9c\u00e9dent Suivant Plus qu\u2019une plateforme d\u2019inscription, un \u00e9cosyst\u00e8me d\u00e9di\u00e9 \u00e0 la vie des clubs d&rsquo;escrime Nos petits plus qui vous facilitent la vie ! Le paiement en plusieurs fois avec le versement int\u00e9gral et imm\u00e9diat. Proposer le paiement en plusieurs fois \u00e0 vos licenci\u00e9s est essentiel pour leur permettre de soulager leur budget sport. Mais cela peut retarder le versement complet des cotisations pour les clubs. Avec SPORTYNEO, vos adh\u00e9rents paient au choix en 1, 4 ou 10 fois, et vous collectez imm\u00e9diatement la totalit\u00e9, gr\u00e2ce \u00e0 une avance de fonds. En savoir plus Plus besoin de g\u00e9rer les demandes d&rsquo;annulation d&rsquo;inscription Proposez une assurance annulation au moment des inscriptions : si votre adh\u00e9rent demande un remboursement, SPORTYNEO l&rsquo;indemnisera sur ses cotisations annuelles ou ses stages. Avec l\u2019assurance facultative SPORTYNEO, d\u00e9finissez une politique claire d&rsquo;annulation et \u00e9vitez les pertes d\u2019argent. C\u2019est l\u2019assurance qui rembourse, pas vous ! En savoir plus Merchandising logot\u00e9 et commissions&#8230; sans rien faire ! Avec la boutique en ligne SPORTYNEO, plus besoin de g\u00e9rer des stocks, des commandes group\u00e9es \u00e0 des fournisseurs et la distribution d&rsquo;\u00e9quipements logot\u00e9s. S\u00e9lectionnez juste les articles qui vous correspondent parmi notre catalogue, et profitez ! Vos adh\u00e9rents passent commande lorsqu&rsquo;ils le souhaitent toute l&rsquo;ann\u00e9e, et sont livr\u00e9s directement chez eux. Encore mieux : 10% de commission vont sont revers\u00e9s sur le montant total des commandes effectu\u00e9es dans l\u2019ann\u00e9e. En savoir plus PAIEMENT FRACTIONN\u00c9 ASSURANCE POUVOIR D\u2019ACHAT MERCHANDISING Offrir un parcours d\u2019adh\u00e9sion simple &amp; rapide \u00e0 vos licenci\u00e9s d&rsquo;escrime Nous cr\u00e9ons ensemble votre page Club en moins d&rsquo;une semaine. 01. Je cr\u00e9e la page de mon club d&rsquo;escrime Je cr\u00e9e la page de mon club d&rsquo;escrime et je mets en ligne mes cotisations, stages et tarifs sp\u00e9ciaux. 02. Je s\u00e9lectionne mes articles de boutique en ligne Je s\u00e9lectionne les goodies &amp; accessoires que mes licenci\u00e9s peuvent commander en toute autonomie. 03. J\u2019envoie le lien de ma page \u00e0 mes licenci\u00e9s d&rsquo;escrime Je communique l\u2019url de ma page Club \u00e0 mes licenci\u00e9s. 04. Je suis mes inscriptions et mes comptes en toute simplicit\u00e9 Je me rends sur mon tableau de bord pour suivre mes statistiques de vente et d&rsquo;inscription en temps r\u00e9el. Je peux cr\u00e9er ma page maintenant pour tester ? Je cr\u00e9e ma page pour mon club d&rsquo;escrime Ce qu&rsquo;en disent nos clients Parce que ce sont eux qui en parlent le mieux\u2026 \u00ab\u00a0Depuis d\u00e9cembre, on a encaiss\u00e9 un CA, juste avec SPORTYNEO, d\u2019un peu plus de 20 000\u20ac. C\u2019est un vrai avantage financier, car si on avait du passer par une banque, elle nous aurait pris 4% dessus.\u00a0\u00bb Sylvain DUFOURNEAUDDirigeant du Poney Club de Val-de-Sa\u00f4ne \u00ab\u00a0SPORTYNEO nous permet d\u2019avoir les r\u00e8glements avant le d\u00e9but du stage alors qu\u2019avant on courait tout le temps apr\u00e8s les r\u00e8glements.\u00a0\u00bb Stanislas TERRIERResponsable de l\u2019\u00e9cole de Tennis d\u2019Annecy \u00ab\u00a0C\u2019est une diversit\u00e9 de paiement pour nos adh\u00e9rents et un gain de temps pour nous au niveau administratif et suivi des commandes.\u00a0\u00bb Dominique TEIXEIRAResponsable sportif du F.C. Geispolsheim \u00ab\u00a0SPORTYNEO nous permet de nous focaliser sur d\u2019autres domaines et de ne pas toujours courir apr\u00e8s les diff\u00e9rents r\u00e8glements.\u00a0\u00bb David MAIREDirigeant du club de l\u2019AS Ludres \u00ab\u00a0L&rsquo;avantage de SPORTYNEO, c&rsquo;est que nous avons une tra\u00e7abilit\u00e9 qui est tr\u00e8s simple, puisque tous les flux financiers passent par le dashboard de l&rsquo;association.\u00a0\u00bb Adrien TURBILResponsable Administratif et Communication du Rouen Normandie Rugby J&rsquo;aimerais utiliser SPORTYNEO pour mon club d&rsquo;escrime Cr\u00e9er ma page C\u2019est gratuit, c\u2019est pratique, c\u2019est sans engagement&#8230; Comment je m\u2019inscris ? Je prends contact avec SPORTYNEO Pour voir concr\u00e8tement \u00e0 quoi ressemble la plateforme, et poser toutes mes questions. Je peux aussi directement cr\u00e9er ma page Club en autonomie. Je signe la convention de partenariat SPORTYNEO est gratuit, mais l\u2019utilisation de la plateforme est soumis \u00e0 la signature d\u2019une convention, afin qu\u2019on puisse vous verser vos recettes et vos commissions. Je cr\u00e9e ma page Club avec mes activit\u00e9s Je rentre mes cotisations, mes stages, mes r\u00e9ductions, et je s\u00e9lectionne mes articles de merchandising. Et hop, je peux recevoir mes inscriptions et mes commandes ! Questions fr\u00e9quentes La plateforme est-elle uniquement accessible aux associations ? Il n\u2019est pas n\u00e9cessaire d\u2019avoir le statut d\u2019association pour b\u00e9n\u00e9ficier de notre plateforme. Elle est accessible \u00e0 tous les clubs, de toutes tailles, que ce soit des assos ou des entreprises comme des centres \u00e9questres. La plateforme est-elle r\u00e9serv\u00e9e aux clubs de sport uniquement ? Elle a initialement \u00e9t\u00e9 con\u00e7ue pour les clubs de sport. Mais les \u00e9coles de musique, clubs de th\u00e9\u00e2tre, BDE, AS sportives (etc.) rencontrent les m\u00eames probl\u00e9matiques, et peuvent utiliser notre plateforme sans soucis. Est-ce que la solution est vraiment gratuite pour mon Club ? Absolument, aucun frais cach\u00e9s, toutes nos fonctionnalit\u00e9s sont 100% gratuites pour les clubs. Comment vous r\u00e9mun\u00e9rez-vous si la solution est gratuite ? Notre r\u00e9mun\u00e9ration se base sur un autre business model, \u00e0 savoir des commissions sur le service facultatif d\u2019assurance, les bons d&rsquo;achat ou le merchandising. Que se passe-t-il si le prelevement de l&rsquo;un de mes adh\u00e9rents ne passe pas sur un paiement en plusieurs fois (carte obsol\u00e8te, fond insuffisant,&#8230;) ? Notre partenaire bancaire s&rsquo;occupe de contacter votre adh\u00e9rent pour mettre \u00e0 jours ses informations de paiement ou reprogrammer un pr\u00e9l\u00e8vement. Dans tous les cas votre tresorerie est s\u00e9curis\u00e9. Sportyneo ne viendra jamais vous demander un remboursement suite \u00e0 un impay\u00e9 de l&rsquo;un de vos adh\u00e9rent. Les adh\u00e9rents peuvent-ils r\u00e9gler leurs cotisations &#038; stages par d\u2019autres moyens qu\u2019en CB ? Tout \u00e0 fait. Chaque Club peut d\u00e9cider d\u2019activer uniquement la CB (ce que nous recommandons pour gagner du temps et \u00e9viter la paperasserie), ou de proposer d\u2019autres moyens comme les ch\u00e8ques et esp\u00e8ces. Peut-on g\u00e9rer les r\u00e9ductions comme le Pass\u2019Sport, Pass R\u00e9gion, ch\u00e8que ANCV, etc. ? Oui la plateforme g\u00e8re tout \u00e7a. Vous pouvez m\u00eame ajouter des<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_6936\" class=\"pvc_stats all\" data-element-id=\"6936\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewbox=\"0 0 502 315\" preserveaspectratio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/new.sportyneo.com\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=\"0\" \/><\/p>\n<div class=\"pvc_clear\"><\/div>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-6936","page","type-page","status-publish","hentry"],"a3_pvc":{"activated":true,"total_views":0,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Landing Page Escrime - Sportyneo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/new.sportyneo.com\/en\/landing-page-escrime\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Landing Page Escrime - Sportyneo\" \/>\n<meta property=\"og:description\" content=\"Le partenaire financier des clubs d&rsquo;escrime Gagnez du temps dans la gestion de votre centre \u00e9questre ! Des paiements facilit\u00e9s en plusieurs fois pour l&rsquo;adh\u00e9rent et une avance de fond pour le gestionnaire. SPORTYNEO s\u2019occupe de tout, vous restez en selle ! Voir la d\u00e9mo Cr\u00e9er ma page Nos partenaires Pr\u00e9c\u00e9dent Suivant Plus qu\u2019une plateforme d\u2019inscription, un \u00e9cosyst\u00e8me d\u00e9di\u00e9 \u00e0 la vie des clubs d&rsquo;escrime Nos petits plus qui vous facilitent la vie ! Le paiement en plusieurs fois avec le versement int\u00e9gral et imm\u00e9diat. Proposer le paiement en plusieurs fois \u00e0 vos licenci\u00e9s est essentiel pour leur permettre de soulager leur budget sport. Mais cela peut retarder le versement complet des cotisations pour les clubs. Avec SPORTYNEO, vos adh\u00e9rents paient au choix en 1, 4 ou 10 fois, et vous collectez imm\u00e9diatement la totalit\u00e9, gr\u00e2ce \u00e0 une avance de fonds. En savoir plus Plus besoin de g\u00e9rer les demandes d&rsquo;annulation d&rsquo;inscription Proposez une assurance annulation au moment des inscriptions : si votre adh\u00e9rent demande un remboursement, SPORTYNEO l&rsquo;indemnisera sur ses cotisations annuelles ou ses stages. Avec l\u2019assurance facultative SPORTYNEO, d\u00e9finissez une politique claire d&rsquo;annulation et \u00e9vitez les pertes d\u2019argent. C\u2019est l\u2019assurance qui rembourse, pas vous ! En savoir plus Merchandising logot\u00e9 et commissions&#8230; sans rien faire ! Avec la boutique en ligne SPORTYNEO, plus besoin de g\u00e9rer des stocks, des commandes group\u00e9es \u00e0 des fournisseurs et la distribution d&rsquo;\u00e9quipements logot\u00e9s. S\u00e9lectionnez juste les articles qui vous correspondent parmi notre catalogue, et profitez ! Vos adh\u00e9rents passent commande lorsqu&rsquo;ils le souhaitent toute l&rsquo;ann\u00e9e, et sont livr\u00e9s directement chez eux. Encore mieux : 10% de commission vont sont revers\u00e9s sur le montant total des commandes effectu\u00e9es dans l\u2019ann\u00e9e. En savoir plus PAIEMENT FRACTIONN\u00c9 ASSURANCE POUVOIR D\u2019ACHAT MERCHANDISING Offrir un parcours d\u2019adh\u00e9sion simple &amp; rapide \u00e0 vos licenci\u00e9s d&rsquo;escrime Nous cr\u00e9ons ensemble votre page Club en moins d&rsquo;une semaine. 01. Je cr\u00e9e la page de mon club d&rsquo;escrime Je cr\u00e9e la page de mon club d&rsquo;escrime et je mets en ligne mes cotisations, stages et tarifs sp\u00e9ciaux. 02. Je s\u00e9lectionne mes articles de boutique en ligne Je s\u00e9lectionne les goodies &amp; accessoires que mes licenci\u00e9s peuvent commander en toute autonomie. 03. J\u2019envoie le lien de ma page \u00e0 mes licenci\u00e9s d&rsquo;escrime Je communique l\u2019url de ma page Club \u00e0 mes licenci\u00e9s. 04. Je suis mes inscriptions et mes comptes en toute simplicit\u00e9 Je me rends sur mon tableau de bord pour suivre mes statistiques de vente et d&rsquo;inscription en temps r\u00e9el. Je peux cr\u00e9er ma page maintenant pour tester ? Je cr\u00e9e ma page pour mon club d&rsquo;escrime Ce qu&rsquo;en disent nos clients Parce que ce sont eux qui en parlent le mieux\u2026 \u00ab\u00a0Depuis d\u00e9cembre, on a encaiss\u00e9 un CA, juste avec SPORTYNEO, d\u2019un peu plus de 20 000\u20ac. C\u2019est un vrai avantage financier, car si on avait du passer par une banque, elle nous aurait pris 4% dessus.\u00a0\u00bb Sylvain DUFOURNEAUDDirigeant du Poney Club de Val-de-Sa\u00f4ne \u00ab\u00a0SPORTYNEO nous permet d\u2019avoir les r\u00e8glements avant le d\u00e9but du stage alors qu\u2019avant on courait tout le temps apr\u00e8s les r\u00e8glements.\u00a0\u00bb Stanislas TERRIERResponsable de l\u2019\u00e9cole de Tennis d\u2019Annecy \u00ab\u00a0C\u2019est une diversit\u00e9 de paiement pour nos adh\u00e9rents et un gain de temps pour nous au niveau administratif et suivi des commandes.\u00a0\u00bb Dominique TEIXEIRAResponsable sportif du F.C. Geispolsheim \u00ab\u00a0SPORTYNEO nous permet de nous focaliser sur d\u2019autres domaines et de ne pas toujours courir apr\u00e8s les diff\u00e9rents r\u00e8glements.\u00a0\u00bb David MAIREDirigeant du club de l\u2019AS Ludres \u00ab\u00a0L&rsquo;avantage de SPORTYNEO, c&rsquo;est que nous avons une tra\u00e7abilit\u00e9 qui est tr\u00e8s simple, puisque tous les flux financiers passent par le dashboard de l&rsquo;association.\u00a0\u00bb Adrien TURBILResponsable Administratif et Communication du Rouen Normandie Rugby J&rsquo;aimerais utiliser SPORTYNEO pour mon club d&rsquo;escrime Cr\u00e9er ma page C\u2019est gratuit, c\u2019est pratique, c\u2019est sans engagement&#8230; Comment je m\u2019inscris ? Je prends contact avec SPORTYNEO Pour voir concr\u00e8tement \u00e0 quoi ressemble la plateforme, et poser toutes mes questions. Je peux aussi directement cr\u00e9er ma page Club en autonomie. Je signe la convention de partenariat SPORTYNEO est gratuit, mais l\u2019utilisation de la plateforme est soumis \u00e0 la signature d\u2019une convention, afin qu\u2019on puisse vous verser vos recettes et vos commissions. Je cr\u00e9e ma page Club avec mes activit\u00e9s Je rentre mes cotisations, mes stages, mes r\u00e9ductions, et je s\u00e9lectionne mes articles de merchandising. Et hop, je peux recevoir mes inscriptions et mes commandes ! Questions fr\u00e9quentes La plateforme est-elle uniquement accessible aux associations ? Il n\u2019est pas n\u00e9cessaire d\u2019avoir le statut d\u2019association pour b\u00e9n\u00e9ficier de notre plateforme. Elle est accessible \u00e0 tous les clubs, de toutes tailles, que ce soit des assos ou des entreprises comme des centres \u00e9questres. La plateforme est-elle r\u00e9serv\u00e9e aux clubs de sport uniquement ? Elle a initialement \u00e9t\u00e9 con\u00e7ue pour les clubs de sport. Mais les \u00e9coles de musique, clubs de th\u00e9\u00e2tre, BDE, AS sportives (etc.) rencontrent les m\u00eames probl\u00e9matiques, et peuvent utiliser notre plateforme sans soucis. Est-ce que la solution est vraiment gratuite pour mon Club ? Absolument, aucun frais cach\u00e9s, toutes nos fonctionnalit\u00e9s sont 100% gratuites pour les clubs. Comment vous r\u00e9mun\u00e9rez-vous si la solution est gratuite ? Notre r\u00e9mun\u00e9ration se base sur un autre business model, \u00e0 savoir des commissions sur le service facultatif d\u2019assurance, les bons d&rsquo;achat ou le merchandising. Que se passe-t-il si le prelevement de l&rsquo;un de mes adh\u00e9rents ne passe pas sur un paiement en plusieurs fois (carte obsol\u00e8te, fond insuffisant,&#8230;) ? Notre partenaire bancaire s&rsquo;occupe de contacter votre adh\u00e9rent pour mettre \u00e0 jours ses informations de paiement ou reprogrammer un pr\u00e9l\u00e8vement. Dans tous les cas votre tresorerie est s\u00e9curis\u00e9. Sportyneo ne viendra jamais vous demander un remboursement suite \u00e0 un impay\u00e9 de l&rsquo;un de vos adh\u00e9rent. Les adh\u00e9rents peuvent-ils r\u00e9gler leurs cotisations &#038; stages par d\u2019autres moyens qu\u2019en CB ? Tout \u00e0 fait. Chaque Club peut d\u00e9cider d\u2019activer uniquement la CB (ce que nous recommandons pour gagner du temps et \u00e9viter la paperasserie), ou de proposer d\u2019autres moyens comme les ch\u00e8ques et esp\u00e8ces. Peut-on g\u00e9rer les r\u00e9ductions comme le Pass\u2019Sport, Pass R\u00e9gion, ch\u00e8que ANCV, etc. ? Oui la plateforme g\u00e8re tout \u00e7a. Vous pouvez m\u00eame ajouter des\" \/>\n<meta property=\"og:url\" content=\"https:\/\/new.sportyneo.com\/en\/landing-page-escrime\/\" \/>\n<meta property=\"og:site_name\" content=\"Sportyneo\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-05T08:35:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/logo-sportyneo-bleu.png\" \/>\n\t<meta property=\"og:image:width\" content=\"4294\" \/>\n\t<meta property=\"og:image:height\" content=\"1344\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"20 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/new.sportyneo.com\\\/landing-page-escrime\\\/\",\"url\":\"https:\\\/\\\/new.sportyneo.com\\\/landing-page-escrime\\\/\",\"name\":\"Landing Page Escrime - Sportyneo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/new.sportyneo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/new.sportyneo.com\\\/landing-page-escrime\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/new.sportyneo.com\\\/landing-page-escrime\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/new.sportyneo.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo-sportyneo-bleu.png\",\"datePublished\":\"2025-04-25T09:16:27+00:00\",\"dateModified\":\"2025-06-05T08:35:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/new.sportyneo.com\\\/landing-page-escrime\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/new.sportyneo.com\\\/landing-page-escrime\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/new.sportyneo.com\\\/landing-page-escrime\\\/#primaryimage\",\"url\":\"https:\\\/\\\/new.sportyneo.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo-sportyneo-bleu.png\",\"contentUrl\":\"https:\\\/\\\/new.sportyneo.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo-sportyneo-bleu.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/new.sportyneo.com\\\/landing-page-escrime\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/new.sportyneo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Landing Page Escrime\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/new.sportyneo.com\\\/#website\",\"url\":\"https:\\\/\\\/new.sportyneo.com\\\/\",\"name\":\"Sportyneo\",\"description\":\"Solutions pour les associations sportives et leurs adh\u00e9rents\",\"publisher\":{\"@id\":\"https:\\\/\\\/new.sportyneo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/new.sportyneo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/new.sportyneo.com\\\/#organization\",\"name\":\"Sportyneo\",\"url\":\"https:\\\/\\\/new.sportyneo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/new.sportyneo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/new.sportyneo.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/cropped-logo-sportyneo-bleu-scaled.png\",\"contentUrl\":\"https:\\\/\\\/new.sportyneo.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/cropped-logo-sportyneo-bleu-scaled.png\",\"width\":2560,\"height\":799,\"caption\":\"Sportyneo\"},\"image\":{\"@id\":\"https:\\\/\\\/new.sportyneo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Landing Page Escrime - Sportyneo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/new.sportyneo.com\/en\/landing-page-escrime\/","og_locale":"en_US","og_type":"article","og_title":"Landing Page Escrime - Sportyneo","og_description":"Le partenaire financier des clubs d&rsquo;escrime Gagnez du temps dans la gestion de votre centre \u00e9questre ! Des paiements facilit\u00e9s en plusieurs fois pour l&rsquo;adh\u00e9rent et une avance de fond pour le gestionnaire. SPORTYNEO s\u2019occupe de tout, vous restez en selle ! Voir la d\u00e9mo Cr\u00e9er ma page Nos partenaires Pr\u00e9c\u00e9dent Suivant Plus qu\u2019une plateforme d\u2019inscription, un \u00e9cosyst\u00e8me d\u00e9di\u00e9 \u00e0 la vie des clubs d&rsquo;escrime Nos petits plus qui vous facilitent la vie ! Le paiement en plusieurs fois avec le versement int\u00e9gral et imm\u00e9diat. Proposer le paiement en plusieurs fois \u00e0 vos licenci\u00e9s est essentiel pour leur permettre de soulager leur budget sport. Mais cela peut retarder le versement complet des cotisations pour les clubs. Avec SPORTYNEO, vos adh\u00e9rents paient au choix en 1, 4 ou 10 fois, et vous collectez imm\u00e9diatement la totalit\u00e9, gr\u00e2ce \u00e0 une avance de fonds. En savoir plus Plus besoin de g\u00e9rer les demandes d&rsquo;annulation d&rsquo;inscription Proposez une assurance annulation au moment des inscriptions : si votre adh\u00e9rent demande un remboursement, SPORTYNEO l&rsquo;indemnisera sur ses cotisations annuelles ou ses stages. Avec l\u2019assurance facultative SPORTYNEO, d\u00e9finissez une politique claire d&rsquo;annulation et \u00e9vitez les pertes d\u2019argent. C\u2019est l\u2019assurance qui rembourse, pas vous ! En savoir plus Merchandising logot\u00e9 et commissions&#8230; sans rien faire ! Avec la boutique en ligne SPORTYNEO, plus besoin de g\u00e9rer des stocks, des commandes group\u00e9es \u00e0 des fournisseurs et la distribution d&rsquo;\u00e9quipements logot\u00e9s. S\u00e9lectionnez juste les articles qui vous correspondent parmi notre catalogue, et profitez ! Vos adh\u00e9rents passent commande lorsqu&rsquo;ils le souhaitent toute l&rsquo;ann\u00e9e, et sont livr\u00e9s directement chez eux. Encore mieux : 10% de commission vont sont revers\u00e9s sur le montant total des commandes effectu\u00e9es dans l\u2019ann\u00e9e. En savoir plus PAIEMENT FRACTIONN\u00c9 ASSURANCE POUVOIR D\u2019ACHAT MERCHANDISING Offrir un parcours d\u2019adh\u00e9sion simple &amp; rapide \u00e0 vos licenci\u00e9s d&rsquo;escrime Nous cr\u00e9ons ensemble votre page Club en moins d&rsquo;une semaine. 01. Je cr\u00e9e la page de mon club d&rsquo;escrime Je cr\u00e9e la page de mon club d&rsquo;escrime et je mets en ligne mes cotisations, stages et tarifs sp\u00e9ciaux. 02. Je s\u00e9lectionne mes articles de boutique en ligne Je s\u00e9lectionne les goodies &amp; accessoires que mes licenci\u00e9s peuvent commander en toute autonomie. 03. J\u2019envoie le lien de ma page \u00e0 mes licenci\u00e9s d&rsquo;escrime Je communique l\u2019url de ma page Club \u00e0 mes licenci\u00e9s. 04. Je suis mes inscriptions et mes comptes en toute simplicit\u00e9 Je me rends sur mon tableau de bord pour suivre mes statistiques de vente et d&rsquo;inscription en temps r\u00e9el. Je peux cr\u00e9er ma page maintenant pour tester ? Je cr\u00e9e ma page pour mon club d&rsquo;escrime Ce qu&rsquo;en disent nos clients Parce que ce sont eux qui en parlent le mieux\u2026 \u00ab\u00a0Depuis d\u00e9cembre, on a encaiss\u00e9 un CA, juste avec SPORTYNEO, d\u2019un peu plus de 20 000\u20ac. C\u2019est un vrai avantage financier, car si on avait du passer par une banque, elle nous aurait pris 4% dessus.\u00a0\u00bb Sylvain DUFOURNEAUDDirigeant du Poney Club de Val-de-Sa\u00f4ne \u00ab\u00a0SPORTYNEO nous permet d\u2019avoir les r\u00e8glements avant le d\u00e9but du stage alors qu\u2019avant on courait tout le temps apr\u00e8s les r\u00e8glements.\u00a0\u00bb Stanislas TERRIERResponsable de l\u2019\u00e9cole de Tennis d\u2019Annecy \u00ab\u00a0C\u2019est une diversit\u00e9 de paiement pour nos adh\u00e9rents et un gain de temps pour nous au niveau administratif et suivi des commandes.\u00a0\u00bb Dominique TEIXEIRAResponsable sportif du F.C. Geispolsheim \u00ab\u00a0SPORTYNEO nous permet de nous focaliser sur d\u2019autres domaines et de ne pas toujours courir apr\u00e8s les diff\u00e9rents r\u00e8glements.\u00a0\u00bb David MAIREDirigeant du club de l\u2019AS Ludres \u00ab\u00a0L&rsquo;avantage de SPORTYNEO, c&rsquo;est que nous avons une tra\u00e7abilit\u00e9 qui est tr\u00e8s simple, puisque tous les flux financiers passent par le dashboard de l&rsquo;association.\u00a0\u00bb Adrien TURBILResponsable Administratif et Communication du Rouen Normandie Rugby J&rsquo;aimerais utiliser SPORTYNEO pour mon club d&rsquo;escrime Cr\u00e9er ma page C\u2019est gratuit, c\u2019est pratique, c\u2019est sans engagement&#8230; Comment je m\u2019inscris ? Je prends contact avec SPORTYNEO Pour voir concr\u00e8tement \u00e0 quoi ressemble la plateforme, et poser toutes mes questions. Je peux aussi directement cr\u00e9er ma page Club en autonomie. Je signe la convention de partenariat SPORTYNEO est gratuit, mais l\u2019utilisation de la plateforme est soumis \u00e0 la signature d\u2019une convention, afin qu\u2019on puisse vous verser vos recettes et vos commissions. Je cr\u00e9e ma page Club avec mes activit\u00e9s Je rentre mes cotisations, mes stages, mes r\u00e9ductions, et je s\u00e9lectionne mes articles de merchandising. Et hop, je peux recevoir mes inscriptions et mes commandes ! Questions fr\u00e9quentes La plateforme est-elle uniquement accessible aux associations ? Il n\u2019est pas n\u00e9cessaire d\u2019avoir le statut d\u2019association pour b\u00e9n\u00e9ficier de notre plateforme. Elle est accessible \u00e0 tous les clubs, de toutes tailles, que ce soit des assos ou des entreprises comme des centres \u00e9questres. La plateforme est-elle r\u00e9serv\u00e9e aux clubs de sport uniquement ? Elle a initialement \u00e9t\u00e9 con\u00e7ue pour les clubs de sport. Mais les \u00e9coles de musique, clubs de th\u00e9\u00e2tre, BDE, AS sportives (etc.) rencontrent les m\u00eames probl\u00e9matiques, et peuvent utiliser notre plateforme sans soucis. Est-ce que la solution est vraiment gratuite pour mon Club ? Absolument, aucun frais cach\u00e9s, toutes nos fonctionnalit\u00e9s sont 100% gratuites pour les clubs. Comment vous r\u00e9mun\u00e9rez-vous si la solution est gratuite ? Notre r\u00e9mun\u00e9ration se base sur un autre business model, \u00e0 savoir des commissions sur le service facultatif d\u2019assurance, les bons d&rsquo;achat ou le merchandising. Que se passe-t-il si le prelevement de l&rsquo;un de mes adh\u00e9rents ne passe pas sur un paiement en plusieurs fois (carte obsol\u00e8te, fond insuffisant,&#8230;) ? Notre partenaire bancaire s&rsquo;occupe de contacter votre adh\u00e9rent pour mettre \u00e0 jours ses informations de paiement ou reprogrammer un pr\u00e9l\u00e8vement. Dans tous les cas votre tresorerie est s\u00e9curis\u00e9. Sportyneo ne viendra jamais vous demander un remboursement suite \u00e0 un impay\u00e9 de l&rsquo;un de vos adh\u00e9rent. Les adh\u00e9rents peuvent-ils r\u00e9gler leurs cotisations &#038; stages par d\u2019autres moyens qu\u2019en CB ? Tout \u00e0 fait. Chaque Club peut d\u00e9cider d\u2019activer uniquement la CB (ce que nous recommandons pour gagner du temps et \u00e9viter la paperasserie), ou de proposer d\u2019autres moyens comme les ch\u00e8ques et esp\u00e8ces. Peut-on g\u00e9rer les r\u00e9ductions comme le Pass\u2019Sport, Pass R\u00e9gion, ch\u00e8que ANCV, etc. ? Oui la plateforme g\u00e8re tout \u00e7a. Vous pouvez m\u00eame ajouter des","og_url":"https:\/\/new.sportyneo.com\/en\/landing-page-escrime\/","og_site_name":"Sportyneo","article_modified_time":"2025-06-05T08:35:30+00:00","og_image":[{"width":4294,"height":1344,"url":"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/logo-sportyneo-bleu.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"20 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/new.sportyneo.com\/landing-page-escrime\/","url":"https:\/\/new.sportyneo.com\/landing-page-escrime\/","name":"Landing Page Escrime - Sportyneo","isPartOf":{"@id":"https:\/\/new.sportyneo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/new.sportyneo.com\/landing-page-escrime\/#primaryimage"},"image":{"@id":"https:\/\/new.sportyneo.com\/landing-page-escrime\/#primaryimage"},"thumbnailUrl":"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/logo-sportyneo-bleu.png","datePublished":"2025-04-25T09:16:27+00:00","dateModified":"2025-06-05T08:35:30+00:00","breadcrumb":{"@id":"https:\/\/new.sportyneo.com\/landing-page-escrime\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/new.sportyneo.com\/landing-page-escrime\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/new.sportyneo.com\/landing-page-escrime\/#primaryimage","url":"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/logo-sportyneo-bleu.png","contentUrl":"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/logo-sportyneo-bleu.png"},{"@type":"BreadcrumbList","@id":"https:\/\/new.sportyneo.com\/landing-page-escrime\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/new.sportyneo.com\/"},{"@type":"ListItem","position":2,"name":"Landing Page Escrime"}]},{"@type":"WebSite","@id":"https:\/\/new.sportyneo.com\/#website","url":"https:\/\/new.sportyneo.com\/","name":"Sportyneo","description":"Solutions for sports associations and their members","publisher":{"@id":"https:\/\/new.sportyneo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/new.sportyneo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/new.sportyneo.com\/#organization","name":"Sportyneo","url":"https:\/\/new.sportyneo.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/new.sportyneo.com\/#\/schema\/logo\/image\/","url":"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/cropped-logo-sportyneo-bleu-scaled.png","contentUrl":"https:\/\/new.sportyneo.com\/wp-content\/uploads\/2024\/10\/cropped-logo-sportyneo-bleu-scaled.png","width":2560,"height":799,"caption":"Sportyneo"},"image":{"@id":"https:\/\/new.sportyneo.com\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"Gr\u00e9goire SPORTYNEO","author_link":"https:\/\/new.sportyneo.com\/en\/author\/communicationsportyneo-com\/"},"uagb_comment_info":0,"uagb_excerpt":"Le partenaire financier des clubs d&rsquo;escrime Gagnez du temps dans la gestion de votre centre \u00e9questre ! Des paiements facilit\u00e9s en plusieurs fois pour l&rsquo;adh\u00e9rent et une avance de fond pour le gestionnaire. SPORTYNEO s\u2019occupe de tout, vous restez en selle ! Voir la d\u00e9mo Cr\u00e9er ma page Nos partenaires Pr\u00e9c\u00e9dent Suivant Plus qu\u2019une plateforme&hellip;","_links":{"self":[{"href":"https:\/\/new.sportyneo.com\/en\/wp-json\/wp\/v2\/pages\/6936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.sportyneo.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/new.sportyneo.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/new.sportyneo.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/new.sportyneo.com\/en\/wp-json\/wp\/v2\/comments?post=6936"}],"version-history":[{"count":10,"href":"https:\/\/new.sportyneo.com\/en\/wp-json\/wp\/v2\/pages\/6936\/revisions"}],"predecessor-version":[{"id":8053,"href":"https:\/\/new.sportyneo.com\/en\/wp-json\/wp\/v2\/pages\/6936\/revisions\/8053"}],"wp:attachment":[{"href":"https:\/\/new.sportyneo.com\/en\/wp-json\/wp\/v2\/media?parent=6936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}